{"id":462,"count":0,"description":"Aspectos relacionados aos benef\u00edcios \u00e0 sa\u00fade do consumo moderado de cava.","link":"https:\/\/alsinac.com\/pt-br\/category\/saude-e-cava\/","name":"Sa\u00fade e cava","slug":"saude-e-cava","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Aspectos relacionados aos benef\u00edcios \u00e0 sa\u00fade do consumo moderado de cava.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/alsinac.com\/pt-br\/category\/saude-e-cava\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/462\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/category\\\/saude-e-cava\\\/#listItem\",\"name\":\"Sa\\u00fade e cava\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/category\\\/saude-e-cava\\\/#listItem\",\"position\":2,\"name\":\"Sa\\u00fade e cava\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/462\\\/#collectionpage\",\"url\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/462\\\/\",\"name\":\"Sa\\u00fade e cava | Bodegas Alsinac\",\"description\":\"Aspectos relacionados aos benef\\u00edcios \\u00e0 sa\\u00fade do consumo moderado de cava.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/462\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/#organization\",\"name\":\"Comprar Cava Online\",\"description\":\"#Comprar Cava Online #\",\"url\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/\",\"email\":\"cavas-alsinac@alsinac.com\",\"telephone\":\"+34930247369\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/alsinac.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/alsinac-logo-gran.png\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/462\\\/#organizationLogo\",\"width\":3561,\"height\":1184},\"image\":{\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/462\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/\",\"name\":\"Bodegas Alsinac\",\"alternateName\":\"Bodegas Alsinac\",\"description\":\"Comprar Cava Online\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/alsinac.com\\\/pt-br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sa\u00fade e cava | Bodegas Alsinac","description":"Aspectos relacionados aos benef\u00edcios \u00e0 sa\u00fade do consumo moderado de cava.","canonical_url":"https:\/\/alsinac.com\/pt-br\/category\/saude-e-cava\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/alsinac.com\/pt-br\/#listItem","position":1,"name":"Inicio","item":"https:\/\/alsinac.com\/pt-br\/","nextItem":{"@type":"ListItem","@id":"https:\/\/alsinac.com\/pt-br\/category\/saude-e-cava\/#listItem","name":"Sa\u00fade e cava"}},{"@type":"ListItem","@id":"https:\/\/alsinac.com\/pt-br\/category\/saude-e-cava\/#listItem","position":2,"name":"Sa\u00fade e cava","previousItem":{"@type":"ListItem","@id":"https:\/\/alsinac.com\/pt-br\/#listItem","name":"Inicio"}}]},{"@type":"CollectionPage","@id":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462\/#collectionpage","url":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462\/","name":"Sa\u00fade e cava | Bodegas Alsinac","description":"Aspectos relacionados aos benef\u00edcios \u00e0 sa\u00fade do consumo moderado de cava.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/alsinac.com\/pt-br\/#website"},"breadcrumb":{"@id":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/alsinac.com\/pt-br\/#organization","name":"Comprar Cava Online","description":"#Comprar Cava Online #","url":"https:\/\/alsinac.com\/pt-br\/","email":"cavas-alsinac@alsinac.com","telephone":"+34930247369","logo":{"@type":"ImageObject","url":"https:\/\/alsinac.com\/wp-content\/uploads\/2020\/03\/alsinac-logo-gran.png","@id":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462\/#organizationLogo","width":3561,"height":1184},"image":{"@id":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/alsinac.com\/pt-br\/#website","url":"https:\/\/alsinac.com\/pt-br\/","name":"Bodegas Alsinac","alternateName":"Bodegas Alsinac","description":"Comprar Cava Online","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/alsinac.com\/pt-br\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/alsinac.com\/pt-br\/\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSa\u00fade e cava\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/alsinac.com\/pt-br\/"},{"label":"Sa\u00fade e cava","link":"https:\/\/alsinac.com\/pt-br\/category\/saude-e-cava\/"}],"_links":{"self":[{"href":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories\/462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/alsinac.com\/pt-br\/wp-json\/wp\/v2\/posts?categories=462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}